{"id":17562,"date":"2022-02-17T13:56:23","date_gmt":"2022-02-17T06:56:23","guid":{"rendered":"https:\/\/w9wellness.com\/?p=17562"},"modified":"2023-09-06T14:38:44","modified_gmt":"2023-09-06T07:38:44","slug":"%d9%85%d8%a7-%d8%a8%d8%b9%d8%af-%d9%83%d9%88%d9%81%d9%8a%d8%af-19","status":"publish","type":"post","link":"https:\/\/w9wellness.com\/ar\/%d9%85%d8%a7-%d8%a8%d8%b9%d8%af-%d9%83%d9%88%d9%81%d9%8a%d8%af-19\/","title":{"rendered":"Long Covid\u060c \u0628\u063a\u0636 \u0627\u0644\u0646\u0638\u0631 \u0639\u0646 \u0644\u0648\u0646 \u0627\u0644\u0645\u0631\u064a\u0636\u060c \u064a\u0645\u0643\u0646 \u0623\u0646 \u064a\u0643\u0648\u0646 \u0644\u062f\u064a\u0643 Long Covid \u0623\u064a\u0636\u064b\u0627."},"content":{"rendered":"<p><span style=\"color:#4a6051\" class=\"has-inline-color\">\u0644\u0642\u062f \u062a\u0633\u0627\u0621\u0644 \u0627\u0644\u0643\u062b\u064a\u0631 \u0645\u0646 \u0627\u0644\u0646\u0627\u0633: <strong>&quot;\u0644\u0642\u062f \u062a\u0639\u0627\u0641\u064a\u062a \u0645\u0646 \u0627\u0644\u0641\u064a\u0631\u0648\u0633 \u0648\u0644\u0643\u0646 \u0644\u0627 \u062a\u0632\u0627\u0644 \u0644\u062f\u064a \u0627\u0644\u0623\u0639\u0631\u0627\u0636.&quot;<\/strong> \u0623\u0648 \u062a\u0638\u0647\u0631 \u0644\u062f\u0649 \u0628\u0639\u0636 \u0627\u0644\u0623\u0634\u062e\u0627\u0635 \u0623\u0639\u0631\u0627\u0636 \u0642\u0644\u064a\u0644\u0629 \u0639\u0646\u062f \u0627\u0644\u0625\u0635\u0627\u0628\u0629 \u0628\u0627\u0644\u0641\u064a\u0631\u0648\u0633. \u0648\u0644\u0643\u0646 \u0628\u0639\u062f \u0627\u0644\u062a\u0639\u0627\u0641\u064a \u0648\u0638\u0647\u0648\u0631 \u0627\u0644\u0645\u0632\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0639\u0631\u0627\u0636 \u0645\u0627 \u0647\u064a \u0627\u0644\u0646\u062f\u0628\u0627\u062a \u0627\u0644\u062a\u064a \u062a\u0631\u0643\u0647\u0627 \u0627\u0644\u0641\u064a\u0631\u0648\u0633 \u0639\u0644\u064a\u0646\u0627\u061f \u0627\u0644\u064a\u0648\u0645 \u062f\u0639\u0648\u0646\u0627 \u0646\u062a\u062d\u062f\u062b \u0639\u0646 Long Covid.<\/span><\/p>\n\n\n\n<p><\/p>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\u0644\u0642\u062f \u062a\u0639\u0627\u0641\u0649 Long Covid \u0645\u0646 \u0627\u0644\u0625\u0635\u0627\u0628\u0629 \u0628\u0627\u0644\u0641\u064a\u0631\u0648\u0633. \u0648\u0644\u0643\u0646 \u0644\u0645\u0627\u0630\u0627 \u0644\u0627 \u062a\u0632\u0627\u0644 \u0627\u0644\u0631\u0627\u0626\u062d\u0629 \u0648\u0627\u0644\u0637\u0639\u0645 \u0643\u0645\u0627 \u0647\u0648\u061f<\/strong><\/h4>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p><span style=\"color:#4a6051\" class=\"has-inline-color\">\u0631\u0628\u0645\u0627 \u064a\u0639\u0631\u0641 \u0627\u0644\u0643\u062b\u064a\u0631 \u0645\u0646 \u0627\u0644\u0646\u0627\u0633 \u0630\u0644\u0643 \u0628\u0627\u0644\u0641\u0639\u0644. <strong>\u0628\u0639\u062f \u0627\u0644\u0625\u0635\u0627\u0628\u0629 \u0628\u0627\u0644\u0641\u064a\u0631\u0648\u0633\u060c \u0633\u062a\u0638\u0644 \u0627\u0644\u0623\u0639\u0631\u0627\u0636 \u062a\u0638\u0647\u0631 \u0643\u0645\u0627 \u0644\u0648 \u0643\u0646\u062a \u0645\u0631\u064a\u0636\u064b\u0627.<\/strong> \u0631\u063a\u0645 \u0623\u0646\u0646\u0627 \u0644\u0645 \u0646\u0643\u062a\u0634\u0641 \u0627\u0644\u0641\u064a\u0631\u0648\u0633 \u0628\u0639\u062f. \u062a\u0645 \u0634\u0641\u0627\u0624\u0647 \u0644\u0623\u0643\u062b\u0631 \u0645\u0646 28 \u064a\u0648\u0645\u064b\u0627 \u0623\u0648 \u0634\u0647\u0631\u064b\u0627 \u0623\u0648 \u0623\u0643\u062b\u0631. \u0647\u0646\u0627\u0643 3 \u0623\u0633\u0628\u0627\u0628 \u0631\u0626\u064a\u0633\u064a\u0629:<\/span><\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p><span style=\"color:#4a6051\" class=\"has-inline-color\"><strong>1. \u0645\u062a\u0644\u0627\u0632\u0645\u0629 \u0645\u0627 \u0628\u0639\u062f \u0627\u0644\u0641\u064a\u0631\u0648\u0633 \u0647\u064a \u0623\u062d\u062f \u0627\u0644\u0623\u0639\u0631\u0627\u0636 \u0628\u0639\u062f \u0627\u0644\u0625\u0635\u0627\u0628\u0629 \u0628\u0627\u0644\u0641\u064a\u0631\u0648\u0633.<\/strong> \u0648\u0627\u0644\u0630\u064a \u064a\u0623\u062a\u064a \u0641\u064a \u0627\u0644\u0648\u0627\u0642\u0639 \u0639\u0628\u0631 \u0643\u0644 \u0641\u064a\u0631\u0648\u0633. \u0645\u0635\u0627\u0628 \u0628\u0627\u0644\u0623\u0646\u0641\u0644\u0648\u0646\u0632\u0627 \u0623\u0648 \u0645\u0631\u0636 \u062e\u0637\u064a\u0631 \u0648\u062f\u062e\u0648\u0644\u0647 \u0627\u0644\u0645\u0633\u062a\u0634\u0641\u0649 <strong>\u0628\u0639\u062f \u062e\u0631\u0648\u062c\u0646\u0627 \u0645\u0646 \u0627\u0644\u0645\u0633\u062a\u0634\u0641\u0649 \u0644\u0646 \u064a\u062a\u0639\u0627\u0641\u0649 \u0627\u0644\u062c\u0633\u0645 \u062c\u064a\u062f\u064b\u0627. \u0644\u0627 \u062a\u0632\u0627\u0644 \u062a\u0634\u0639\u0631 \u0628\u0627\u0644\u062a\u0639\u0628 \u0648\u0627\u0644\u0625\u0631\u0647\u0627\u0642 \u0648\u0639\u062f\u0645 \u0627\u0644\u0634\u0639\u0648\u0631 \u0628\u0627\u0644\u0627\u0646\u062a\u0639\u0627\u0634.<\/strong> <strong>\u064a\u0628\u062f\u0648 \u0627\u0644\u0623\u0645\u0631 \u0643\u0645\u0627 \u0644\u0648 \u0623\u0646\u0646\u0627 \u0642\u0627\u062a\u0644\u0646\u0627 \u0644\u0644\u062a\u0648\u060c \u0648\u062e\u0636\u0646\u0627 \u062d\u0631\u0628\u064b\u0627. <\/strong>\u062a\u0645\u0627\u0645\u064b\u0627 \u0645\u062b\u0644 \u0627\u0644\u062c\u0646\u062f\u064a \u0627\u0644\u0639\u0627\u0626\u062f\u060c \u064a\u062c\u0628 \u0639\u0644\u064a\u0647 \u0623\u0646 \u064a\u062a\u0639\u0627\u0641\u0649. \u0641\u064a \u0628\u0639\u0636 \u0627\u0644\u0623\u062d\u064a\u0627\u0646 \u062a\u0633\u062a\u0645\u0631 \u0627\u0644\u062d\u0631\u0648\u0628 \u0644\u0641\u062a\u0631\u0629 \u0637\u0648\u064a\u0644\u0629. \u0639\u0646\u062f \u0627\u0644\u0639\u0648\u062f\u0629\u060c \u0642\u062f \u064a\u0643\u0648\u0646 \u0627\u0644\u062c\u0646\u0648\u062f \u0641\u064a \u0628\u0639\u0636 \u0627\u0644\u0623\u062d\u064a\u0627\u0646 \u0645\u0631\u0647\u0642\u064a\u0646 \u062c\u0633\u062f\u064a\u064b\u0627 \u0648\u0639\u0642\u0644\u064a\u064b\u0627. \u0644\u0627 \u064a\u0632\u0627\u0644 \u064a\u062c\u0639\u0644\u0646\u064a \u0623\u0634\u0639\u0631 \u0628\u0627\u0644\u0627\u0643\u062a\u0626\u0627\u0628. \u0623\u0645 \u0623\u0646\u0647\u0627 \u0634\u062f\u064a\u062f\u0629 \u0644\u062f\u0631\u062c\u0629 \u0623\u0646\u0646\u0627 \u0646\u0633\u0645\u064a\u0647\u0627<strong>\u0627\u0636\u0637\u0631\u0627\u0628 \u0645\u0627 \u0628\u0639\u062f \u0627\u0644\u0635\u062f\u0645\u0629 (\u0627\u0636\u0637\u0631\u0627\u0628 \u0645\u0627 \u0628\u0639\u062f \u0627\u0644\u0635\u062f\u0645\u0629)<\/strong> \u0641\u064a \u0627\u0644\u0648\u0627\u0642\u0639\u060c \u0647\u0646\u0627\u0643 \u0623\u0634\u062e\u0627\u0635 \u064a\u062a\u062d\u062f\u062b\u0648\u0646 \u0639\u0646 \u0646\u0641\u0633 \u0627\u0644\u0634\u064a\u0621. <strong>\u0627\u0636\u0637\u0631\u0627\u0628 \u0645\u0627 \u0628\u0639\u062f \u0627\u0644\u0635\u062f\u0645\u0629 \u0628\u0639\u062f \u0627\u0644\u0625\u0635\u0627\u0628\u0629 \u0628\u0627\u0644\u0641\u064a\u0631\u0648\u0633 \u0648\u062c\u062f \u062d\u0648\u0627\u0644\u064a 30% \u0623\u0648 10 \u0623\u0634\u062e\u0627\u0635 \u0648\u062c\u062f 3 \u0623\u0634\u062e\u0627\u0635 \u064a\u0639\u0627\u0646\u0648\u0646 \u0645\u0646 \u0627\u0636\u0637\u0631\u0627\u0628 \u0645\u0627 \u0628\u0639\u062f \u0627\u0644\u0635\u062f\u0645\u0629.<\/strong> \u0623\u064a \u0627\u0644\u0627\u0643\u062a\u0626\u0627\u0628 \u0628\u0639\u062f \u062a\u0639\u0627\u0641\u064a\u0646\u0627 \u0644\u0623\u0643\u062b\u0631 \u0645\u0646 \u0634\u0647\u0631 \u0623\u0648 \u0623\u0643\u062b\u0631.&nbsp;<\/span><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/w9wellness.com\/wp-content\/uploads\/2022\/01\/Post-viral-syndrome-\u0e40\u0e1b\u0e47\u0e19\u0e2d\u0e32\u0e01\u0e32\u0e23\u0e2b\u0e25\u0e31\u0e07\u0e15\u0e34\u0e14\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e44\u0e27\u0e23\u0e31\u0e2a.jpg\" alt=\"\u0643\u0648\u0641\u064a\u062f \u0637\u0648\u064a\u0644 \u0627\u0644\u0623\u0645\u062f\" class=\"wp-image-17569\"\/><\/figure><\/div>\n\n\n\n<div class=\"wp-block-buttons aligncenter is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-background no-border-radius\" href=\"https:\/\/w9wellness.com\/ar\/%d9%85%d8%b9%d8%b2%d8%b2-%d8%a7%d9%84%d9%85%d9%86%d8%a7%d8%b9%d8%a9\/\" style=\"background-color:#ba0c49\">\u062a\u0639\u0632\u064a\u0632 \u0627\u0644\u0645\u0646\u0627\u0639\u0629<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/w9wellness.com\/wp-content\/uploads\/2022\/01\/2.-MIS-Multiorgan-inflammatory-syndrome-\u0e04\u0e37\u0e2d\u0e2d\u0e27\u0e31\u0e22\u0e27\u0e30\u0e15\u0e48\u0e32\u0e07\u0e46-\u0e22\u0e31\u0e07\u0e2d\u0e31\u0e01\u0e40\u0e2a\u0e1a\u0e2d\u0e22\u0e39\u0e48-\u0e41\u0e21\u0e49\u0e27\u0e48\u0e32\u0e23\u0e48\u0e32\u0e07\u0e01\u0e32\u0e22\u0e08\u0e30\u0e2b\u0e32\u0e22\u0e21\u0e32\u0e41\u0e25\u0e49\u0e27\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e14\u0e37\u0e2d\u0e19.jpg\" alt=\"\u0643\u0648\u0641\u064a\u062f \u0637\u0648\u064a\u0644 \u0627\u0644\u0623\u0645\u062f\" class=\"wp-image-17571\"\/><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p><span style=\"color:#4a6051\" class=\"has-inline-color\"><strong>2.<\/strong> <strong>MIS (\u0645\u062a\u0644\u0627\u0632\u0645\u0629 \u0627\u0644\u0627\u0644\u062a\u0647\u0627\u0628\u0627\u062a \u0627\u0644\u0645\u062a\u0639\u062f\u062f\u0629 \u0627\u0644\u0623\u0639\u0636\u0627\u0621)<\/strong> <strong>\u0647\u064a \u0623\u062c\u0647\u0632\u0629 \u0645\u062e\u062a\u0644\u0641\u0629 \u0644\u0627 \u062a\u0632\u0627\u0644 \u0645\u0644\u062a\u0647\u0628\u0629 \u0639\u0644\u0649 \u0627\u0644\u0631\u063a\u0645 \u0645\u0646 \u0634\u0641\u0627\u0621 \u0627\u0644\u062c\u0633\u0645 \u0644\u0645\u062f\u0629 \u0634\u0647\u0631<\/strong> \u0628\u0639\u062f \u0642\u064a\u0627\u0633 \u0627\u0644\u0627\u0644\u062a\u0647\u0627\u0628 \u0641\u064a \u0627\u0644\u062f\u0645<strong>\u0648\u0648\u062c\u062f\u0646\u0627 \u0623\u064a\u0636\u064b\u0627 \u0623\u0646 \u0645\u0633\u062a\u0648\u064a\u0627\u062a \u0627\u0644\u0627\u0644\u062a\u0647\u0627\u0628 \u0641\u064a \u0627\u0644\u062f\u0645 \u0644\u0627 \u062a\u0632\u0627\u0644 \u0645\u0631\u062a\u0641\u0639\u0629.<\/strong> \u0642\u0627\u0631\u0646\u0647\u0627 \u0628\u0627\u0644\u0646\u0627\u0631 \u0627\u0644\u062a\u064a \u0644\u0645 \u062a\u0646\u0637\u0641\u0626 \u0628\u0627\u0644\u0643\u0627\u0645\u0644 \u0628\u0639\u062f. \u0644\u0627 \u062a\u0632\u0627\u0644 \u0647\u0646\u0627\u0643 \u0646\u0627\u0631 \u0641\u064a \u0627\u0644\u062c\u0633\u0645. \u0644\u0627 \u064a\u0632\u0627\u0644 \u0647\u0646\u0627\u0643 \u0627\u0644\u062a\u0647\u0627\u0628. \u0623\u0648 \u062d\u0627\u0648\u0644 \u0623\u0646 \u062a\u0641\u0643\u0631 \u0641\u064a \u062d\u0631\u064a\u0642 \u063a\u0627\u0628\u0629 \u064a\u0646\u062a\u0634\u0631. <strong>\u0641\u064a \u0628\u0639\u0636 \u0627\u0644\u0623\u062d\u064a\u0627\u0646 \u0642\u062f \u064a\u0633\u062a\u063a\u0631\u0642 \u0627\u0644\u0623\u0645\u0631 \u0623\u0633\u0627\u0628\u064a\u0639 \u0623\u0648 \u0623\u062d\u064a\u0627\u0646\u064b\u0627 \u062d\u062a\u0649 \u0623\u0634\u0647\u0631 \u062d\u062a\u0649 \u064a\u062e\u062a\u0641\u064a \u062a\u0645\u0627\u0645\u064b\u0627.<\/strong> \u0625\u0630\u0627 \u0643\u0627\u0646 \u0647\u0646\u0627\u0643 \u0627\u0644\u0643\u062b\u064a\u0631 \u0645\u0646 \u062d\u0631\u0627\u0626\u0642 \u0627\u0644\u063a\u0627\u0628\u0627\u062a \u064a\u062c\u0628 \u0623\u0646 \u064a\u0643\u0648\u0646 \u0627\u0644\u0623\u0645\u0631 \u0645\u062a\u0631\u0648\u0643\u064b\u0627 \u0644\u0641\u0631\u064a\u0642 \u0645\u0643\u0627\u0641\u062d\u0629 \u0627\u0644\u062d\u0631\u0627\u0626\u0642 \u0644\u062f\u064a\u0646\u0627 \u0644\u0645\u0639\u0631\u0641\u0629 \u0645\u0627 \u0625\u0630\u0627 \u0643\u0627\u0646 \u0647\u0646\u0627\u0643 \u0645\u0627 \u064a\u0643\u0641\u064a \u0645\u0646\u0647\u0645 \u0623\u0645 \u0644\u0627. \u0641\u0625\u0630\u0627 \u0632\u0627\u062f \u0639\u062f\u062f \u0641\u0631\u0642 \u0627\u0644\u0625\u0637\u0641\u0627\u0621 \u0644\u062f\u064a\u0646\u0627\u060c \u0639\u0644\u0649 \u0633\u0628\u064a\u0644 \u0627\u0644\u0645\u062b\u0627\u0644\u060c \u0642\u0644\u0651\u062a \u0645\u0636\u0627\u062f\u0627\u062a \u0627\u0644\u0623\u0643\u0633\u062f\u0629 \u0644\u062f\u064a\u0646\u0627. \u0642\u062f \u064a\u062a\u0633\u0628\u0628 \u0641\u064a \u0627\u0646\u062a\u0634\u0627\u0631 \u0627\u0644\u0646\u0627\u0631 \u0628\u0634\u0643\u0644 \u0645\u0633\u062a\u0645\u0631 \u0648\u0633\u064a\u0633\u062a\u0645\u0631 \u0627\u0644\u0627\u0644\u062a\u0647\u0627\u0628 \u0641\u064a \u0627\u0644\u0627\u0646\u062a\u0634\u0627\u0631. \u064a\u0633\u0628\u0628 \u0627\u0644\u062a\u0647\u0627\u0628\u0627\u062a \u0641\u064a \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0639\u0636\u0627\u0621.<\/span><\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p><span style=\"color:#4a6051\" class=\"has-inline-color\"><strong>3. \u0627\u0644\u062a\u0644\u064a\u0641 \u0647\u0648 \u0646\u0633\u064a\u062c \u0644\u064a\u0641\u064a \u063a\u064a\u0631 \u0637\u0628\u064a\u0639\u064a. \u0628\u0639\u062f \u062a\u062f\u0645\u064a\u0631 \u0627\u0644\u0623\u0646\u0633\u062c\u0629 \u0627\u0644\u0637\u0628\u064a\u0639\u064a\u0629 <\/strong>\u0628\u0627\u0644\u0645\u0642\u0627\u0631\u0646\u0629 \u0645\u0639 \u0623\u0646\u0642\u0627\u0636 \u0627\u0644\u062d\u0631\u0628 \u0627\u0644\u062a\u064a \u062a\u0645 \u062a\u062f\u0645\u064a\u0631\u0647\u0627 \u0628\u0627\u0644\u0641\u0639\u0644. \u0643\u0644 \u0634\u064a\u0621 \u0639\u0646 \u0627\u0644\u0631\u0626\u062a\u064a\u0646<strong> \u0623\u0646\u0633\u062c\u0629 \u0627\u0644\u0631\u0626\u0629 \u0627\u0644\u0644\u064a\u0641\u064a\u0629 \u0627\u0644\u0623\u0646\u0633\u062c\u0629 \u0627\u0644\u0639\u0636\u0644\u064a\u0629 \u0623\u0646\u0633\u062c\u0629 \u0639\u0635\u0628\u064a\u0629<\/strong> \u062c\u0645\u064a\u0639 \u0627\u0644\u0623\u062c\u0647\u0632\u0629 \u0627\u0644\u0639\u0635\u0628\u064a\u0629 \u0627\u0644\u062a\u064a \u0631\u0628\u0645\u0627 \u0644\u0645 \u062a\u0639\u062f\u060c \u0628\u0645\u0627 \u0641\u064a \u0630\u0644\u0643 \u062d\u0627\u0633\u0629 \u0627\u0644\u062a\u0630\u0648\u0642 \u0648\u0627\u0644\u0634\u0645 \u0623\u0648 \u062e\u062f\u0631 \u0627\u0644\u064a\u062f\u064a\u0646 \u0648\u0627\u0644\u0642\u062f\u0645\u064a\u0646 <strong>\u0631\u0628\u0645\u0627 \u0644\u0645 \u064a\u0639\u062f 100% \u0628\u0639\u062f<\/strong> \u062e\u0627\u0635\u0629 \u0623\u0646\u0647 \u0642\u062f \u0641\u0642\u062f \u0628\u0627\u0644\u0641\u0639\u0644. <strong>\u0627\u0644\u062a\u0639\u0627\u0641\u064a \u064a\u0633\u062a\u063a\u0631\u0642 \u0648\u0642\u062a\u0627. \u0641\u064a \u0628\u0639\u0636 \u0627\u0644\u0623\u062d\u064a\u0627\u0646 \u0642\u062f \u064a\u0633\u062a\u0645\u0631 \u0644\u0639\u062f\u0629 \u0623\u0634\u0647\u0631.<\/strong> \u062d\u062a\u0649 \u064a\u062a\u0645 \u0627\u0633\u062a\u0639\u0627\u062f\u0629 \u0627\u0644\u0623\u0646\u0633\u062c\u0629 \u0627\u0644\u062c\u062f\u064a\u062f\u0629 \u062a\u062f\u0631\u064a\u062c\u064a\u0627. \u0647\u0630\u0647 \u0643\u0644 \u0627\u0644\u0623\u0633\u0628\u0627\u0628 \u0627\u0644\u062a\u064a \u062a\u0633\u0628\u0628 \u0645\u0631\u0636 Long Covid.<\/span><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/w9wellness.com\/wp-content\/uploads\/2022\/01\/3.-\u0e2a\u0e38\u0e14\u0e17\u0e49\u0e32\u0e22\u0e04\u0e37\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e40\u0e2a\u0e35\u0e22\u0e2b\u0e32\u0e22\u0e17\u0e35\u0e48\u0e21\u0e31\u0e19\u0e40\u0e01\u0e34\u0e14\u0e02\u0e36\u0e49\u0e19\u0e44\u0e1b\u0e41\u0e25\u0e49\u0e27\u0e2b\u0e23\u0e37\u0e2d\u0e42\u0e14\u0e19\u0e17\u0e33\u0e25\u0e32\u0e22\u0e44\u0e1b\u0e41\u0e25\u0e49\u0e27.jpg\" alt=\"\u0643\u0648\u0641\u064a\u062f \u0637\u0648\u064a\u0644 \u0627\u0644\u0623\u0645\u062f\" class=\"wp-image-17573\"\/><\/figure><\/div>\n<\/div>\n<\/div>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\u064a\u0645\u0643\u0646 \u0644\u0645\u0631\u0636\u0649 \u0627\u0644\u0644\u0648\u0646 \u0627\u0644\u0623\u062e\u0636\u0631 \u0623\u064a\u0636\u064b\u0627 \u062a\u062c\u0631\u0628\u0629 \u0643\u0648\u0641\u064a\u062f.<\/strong> <strong>\u064a\u0645\u0643\u0646\u0643 \u0627\u0644\u062d\u0635\u0648\u0644 \u0639\u0644\u0649 \u0646\u0641\u0633 \u0627\u0644\u0634\u064a\u0621\u061f<\/strong><\/h4>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p><span style=\"color:#4a6051\" class=\"has-inline-color\">\u0648\u062a\u0634\u0645\u0644 \u0627\u0644\u0639\u062f\u064a\u062f \u0645\u0646 \u0627\u0644\u062f\u0631\u0627\u0633\u0627\u062a \u0627\u0644\u0628\u062d\u062b\u064a\u0629<strong>&nbsp;\u0645\u0631\u0643\u0632 \u0627\u0644\u0633\u064a\u0637\u0631\u0629 \u0639\u0644\u0649 \u0627\u0644\u0623\u0645\u0631\u0627\u0636<\/strong>&nbsp;(\u0645\u0631\u0627\u0643\u0632 \u0627\u0644\u0633\u064a\u0637\u0631\u0629 \u0639\u0644\u0649 \u0627\u0644\u0623\u0645\u0631\u0627\u0636 \u0648\u0627\u0644\u0648\u0642\u0627\u064a\u0629 \u0645\u0646\u0647\u0627) \u062e\u0631\u062c\u062a \u0623\u064a\u0636\u064b\u0627 \u0644\u062a\u0642\u0648\u0644 \u0630\u0644\u0643&nbsp;<strong>\u00ab\u0627\u0644\u0623\u0639\u0631\u0627\u0636 \u0628\u0639\u062f \u0627\u0644\u0625\u0635\u0627\u0628\u0629 \u0628\u0627\u0644\u0641\u064a\u0631\u0648\u0633 \u0644\u0627 \u0639\u0644\u0627\u0642\u0629 \u0644\u0647\u0627 \u0628\u062e\u0637\u0648\u0631\u0629 \u0627\u0644\u0645\u0631\u0636\u00bb<\/strong>&nbsp;\u0647\u0630\u0627 \u064a\u0639\u0646\u064a \u0623\u0646\u0643 \u0641\u064a \u0627\u0644\u0645\u0633\u062a\u0634\u0641\u0649 \u0623\u0648 \u0641\u064a \u0639\u0632\u0644\u0629 \u0645\u0646\u0632\u0644\u064a\u0629\u060c \u0633\u0648\u0627\u0621 \u0643\u0646\u062a \u0645\u0635\u0627\u0628\u064b\u0627 \u0628\u0645\u0631\u0636 \u062e\u0637\u064a\u0631 \u0623\u0648 \u0628\u0645\u0631\u0636 \u062e\u0641\u064a\u0641<strong>\u0623\u0639\u0631\u0627\u0636 \u0627\u0644\u0645\u0631\u0636 \u0628\u0639\u062f \u0627\u0644\u0625\u0635\u0627\u0628\u0629 \u0628\u0627\u0644\u0641\u064a\u0631\u0648\u0633 \u0647\u064a \u0646\u0641\u0633\u0647\u0627 \u062a\u0642\u0631\u064a\u0628\u064b\u0627 \u0623\u0639\u0631\u0627\u0636 50%.<\/strong>&nbsp;\u0647\u0630\u0627 \u064a\u0639\u0646\u064a \u0623\u0646\u0647 \u0639\u0646\u062f\u0645\u0627 \u0643\u0646\u062a \u0645\u0631\u064a\u0636\u064b\u0627 \u0643\u0627\u0646 \u0644\u062f\u064a\u0643 \u0623\u0639\u0631\u0627\u0636 \u0642\u0644\u064a\u0644\u0629. \u0648\u0644\u0643\u0646 \u0628\u0639\u062f \u0627\u0644\u062a\u0639\u0627\u0641\u064a\u060c \u0644\u0627 \u064a\u0632\u0627\u0644 \u0645\u0646 \u0627\u0644\u0645\u0645\u0643\u0646 \u0638\u0647\u0648\u0631 \u0627\u0644\u0645\u0632\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0639\u0631\u0627\u0636.<\/span><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><a href=\"https:\/\/www.youtube.com\/watch?v=3enArTZyJ4Y\"><img decoding=\"async\" src=\"https:\/\/w9wellness.com\/wp-content\/uploads\/2022\/02\/\u0e27\u0e34\u0e14\u0e35\u0e42\u0e2d\u0e25\u0e2d\u0e07\u0e42\u0e04\u0e27\u0e34\u0e14-ep.1.png\" alt=\"\u0643\u0648\u0641\u064a\u062f \u0637\u0648\u064a\u0644 \u0627\u0644\u0623\u0645\u062f\" class=\"wp-image-17937\"\/><\/a><\/figure><\/div>\n<\/div>\n<\/div>\n\n\n\n<h4 class=\"wp-block-heading\"><strong>\u0645\u062b\u0627\u0644 \u0644\u062d\u0627\u0644\u0629 \u0645\u0631\u064a\u0636 \u0638\u0647\u0631\u062a \u0639\u0644\u064a\u0647 \u0627\u0644\u0623\u0639\u0631\u0627\u0636 \u0628\u0639\u062f \u0625\u0635\u0627\u0628\u062a\u0647 \u0628\u0627\u0644\u0641\u064a\u0631\u0648\u0633<\/strong><\/h4>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-large\"><img decoding=\"async\" src=\"https:\/\/w9wellness.com\/wp-content\/uploads\/2022\/01\/\u0e40\u0e04\u0e2a\u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e04\u0e19\u0e44\u0e02\u0e49\u0e17\u0e35\u0e48\u0e21\u0e35\u0e2d\u0e32\u0e01\u0e32\u0e23\u0e25\u0e2d\u0e07\u0e42\u0e04\u0e27\u0e34\u0e14.jpg\" alt=\"\u0643\u0648\u0641\u064a\u062f \u0637\u0648\u064a\u0644 \u0627\u0644\u0623\u0645\u062f\" class=\"wp-image-17575\"\/><\/figure><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p><span style=\"color:#4a6051\" class=\"has-inline-color\">\u0643\u0627\u0646 \u0647\u0646\u0627\u0643 \u0632\u0648\u062c \u0645\u0646 \u0627\u0644\u0645\u0631\u0636\u0649 \u0627\u0644\u0630\u064a\u0646 \u062c\u0627\u0621\u0648\u0627 \u0644\u0627\u0633\u062a\u0634\u0627\u0631\u0629 \u0627\u0644\u0637\u0628\u064a\u0628. \u064a\u0643\u0648\u0646 \u0627\u0644\u0632\u0648\u062c \u0648\u0627\u0644\u0632\u0648\u062c\u0629 <strong>\u0639\u0646\u062f\u0645\u0627 \u0643\u0646\u062a \u0645\u0631\u064a\u0636\u064b\u0627\u060c \u0643\u0627\u0646 \u0632\u0648\u062c\u064a \u0645\u0631\u064a\u0636\u064b\u0627 \u0628\u0634\u0643\u0644 \u062e\u0637\u064a\u0631 \u0648\u0627\u0636\u0637\u0631 \u0625\u0644\u0649 \u062f\u062e\u0648\u0644 \u0627\u0644\u0645\u0633\u062a\u0634\u0641\u0649. \u0644\u062f\u064a\u0643 \u0623\u0639\u0631\u0627\u0636 \u062d\u0627\u062f\u0629 \u0644\u0643\u0646 \u062d\u0627\u0644\u0629 \u0632\u0648\u062c\u062a\u0647 \u062e\u0641\u064a\u0641\u0629 \u0646\u0633\u0628\u064a\u0627 \u0648\u0644\u0627 \u062a\u0638\u0647\u0631 \u0639\u0644\u064a\u0647\u0627 \u0633\u0648\u0649 \u0623\u0639\u0631\u0627\u0636 \u0628\u0633\u064a\u0637\u0629 \u0648\u064a\u0645\u0643\u0646 \u0639\u0644\u0627\u062c\u0647\u0627 \u0641\u064a \u0627\u0644\u0645\u0646\u0632\u0644. \u0644\u0643\u0646 \u0628\u0639\u062f \u062a\u0639\u0627\u0641\u064a\u0647 \u062a\u0628\u064a\u0646 \u0623\u0646 \u0627\u0644\u0632\u0648\u062c \u0623\u0635\u0628\u062d \u0642\u0627\u062f\u0631\u0627\u064b \u0639\u0644\u0649 \u0623\u0646 \u064a\u0639\u064a\u0634 \u062d\u064a\u0627\u0629 \u0637\u0628\u064a\u0639\u064a\u0629. <\/strong>\u0627\u0644\u0623\u0639\u0631\u0627\u0636 \u0628\u0639\u062f \u0627\u0644\u0625\u0635\u0627\u0628\u0629 \u0628\u0627\u0644\u0641\u064a\u0631\u0648\u0633 \u0646\u0627\u062f\u0631\u0629 \u062c\u062f\u064b\u0627. <strong>\u0644\u0643\u0646 \u0632\u0648\u062c\u062a\u0647 \u0645\u0627 \u0632\u0627\u0644\u062a \u062a\u0634\u0639\u0631 \u0628\u0627\u0644\u062a\u0648\u0639\u0643. \u0628\u0627\u0644\u0625\u0636\u0627\u0641\u0629 \u0625\u0644\u0649 \u0623\u0646\u0647\u0627 \u062a\u0628\u062f\u0648 \u0645\u0631\u064a\u0636\u0629 \u0623\u0643\u062b\u0631 \u0645\u0645\u0627 \u0643\u0627\u0646\u062a \u0639\u0644\u064a\u0647 \u0639\u0646\u062f\u0645\u0627 \u0643\u0627\u0646\u062a \u0645\u0631\u064a\u0636\u0629. <\/strong>\u0648\u0627\u0644\u0630\u064a \u062a\u0645 \u0639\u0644\u0627\u062c\u0647 \u0644\u0645\u062f\u0629 \u0634\u0647\u0631 \u0627\u0644\u0622\u0646 \u0648\u0644\u0643\u0646 \u0644\u0645 \u064a\u062a\u0645 \u0634\u0641\u0627\u0621\u0647 \u0628\u0639\u062f.<strong> \u0639\u0644\u0649 \u0627\u0644\u0631\u063a\u0645 \u0645\u0646 \u0645\u062d\u0627\u0648\u0644\u0629 \u0627\u0644\u062a\u0639\u0627\u0641\u064a \u0645\u062d\u0627\u0648\u0644\u0629 \u0627\u0644\u0639\u0648\u062f\u0629 \u0625\u0644\u0649 \u0645\u0645\u0627\u0631\u0633\u0629 \u0627\u0644\u062c\u0631\u064a \u0648\u0645\u0645\u0627\u0631\u0633\u0629 \u0627\u0644\u0631\u064a\u0627\u0636\u0629. \u0648\u0644\u0643\u0646 \u0627\u062a\u0636\u062d \u0630\u0644\u0643 &quot;\u0627\u0644\u062c\u0631\u064a \u064a\u062c\u0639\u0644\u0643 \u0645\u062a\u0639\u0628\u064b\u0627 \u0623\u0643\u062b\u0631 \u0645\u0646 \u0627\u0644\u0645\u0639\u062a\u0627\u062f.&quot;<\/strong><\/span><\/p>\n<\/div>\n<\/div>\n\n\n\n<p><span style=\"color:#4a6051\" class=\"has-inline-color\">\u0623\u0634\u0639\u0631 \u0648\u0643\u0623\u0646\u0646\u064a \u0644\u0627 \u0623\u062a\u0646\u0641\u0633 \u0628\u0634\u0643\u0644 \u062c\u064a\u062f. \u0623\u0634\u0639\u0631 \u0628\u0627\u0644\u062a\u0639\u0628\u060c \u0648\u0627\u0644\u0634\u0639\u0648\u0631 \u0628\u0627\u0644\u0625\u0631\u0647\u0627\u0642\u060c \u0648\u0627\u0644\u0634\u0639\u0648\u0631 \u0628\u0623\u0646 \u0639\u0642\u0644\u064a \u0644\u0627 \u064a\u0639\u0645\u0644 \u0628\u0634\u0643\u0644 \u062c\u064a\u062f\u060c \u0648\u0639\u062f\u0645 \u0627\u0644\u0642\u062f\u0631\u0629 \u0639\u0644\u0649 \u0627\u0644\u062a\u0631\u0643\u064a\u0632. \u0639\u0646\u062f\u0645\u0627 \u0623\u0639\u0645\u0644\u060c \u0623\u0634\u0639\u0631 \u0623\u0646\u0646\u064a \u063a\u064a\u0631 \u0642\u0627\u062f\u0631 \u0639\u0644\u0649 \u0627\u0644\u062a\u0631\u0643\u064a\u0632 \u0641\u064a \u0639\u0645\u0644\u064a \u0643\u0645\u0627 \u0643\u0627\u0646 \u0645\u0646 \u0642\u0628\u0644. \u0644\u0623\u0646\u0647 \u0644\u0627 \u062a\u0632\u0627\u0644 \u0647\u0646\u0627\u0643 \u0623\u0639\u0631\u0627\u0636 \u0643\u062b\u064a\u0631\u0629.<strong> \u0628\u0645\u0627 \u0641\u064a \u0630\u0644\u0643 \u0623\u0639\u0631\u0627\u0636 \u0639\u062f\u0645 \u0627\u0644\u0642\u062f\u0631\u0629 \u0639\u0644\u0649 \u0627\u0644\u062a\u0630\u0648\u0642 \u0623\u0648 \u0627\u0644\u0634\u0645\u060c \u0644\u0627 \u062a\u0632\u0627\u0644 \u0645\u0648\u062c\u0648\u062f\u0629 \u0645\u0646\u0630 \u0638\u0647\u0648\u0631 \u0641\u064a\u0631\u0648\u0633 \u0643\u0648\u0631\u0648\u0646\u0627. \u0639\u0644\u0649 \u0627\u0644\u0631\u063a\u0645 \u0645\u0646 \u0645\u0631\u0648\u0631 \u0634\u0647\u0631 \u0645\u0646\u0630 \u0623\u0646 \u062a\u0639\u0627\u0641\u064a\u062a\u060c \u0625\u0644\u0627 \u0623\u0646 \u0627\u0644\u0623\u0645\u0631 \u0644\u0627 \u064a\u0632\u0627\u0644 \u0644\u064a\u0633 \u0623\u0641\u0636\u0644.<\/strong> \u0641\u0634\u0639\u0631\u062a \u0628\u0627\u0644\u062e\u0648\u0641 \u0645\u0646 \u0623\u0644\u0627 \u064a\u0632\u0648\u0644 \u0627\u0644\u0623\u0645\u0631\u060c \u0641\u062c\u0626\u062a \u0644\u0627\u0633\u062a\u0634\u0627\u0631\u0629 \u0637\u0628\u064a\u0628. \u0648\u0647\u0630\u0627 \u0645\u062b\u0627\u0644 \u0622\u062e\u0631 \u064a\u0642\u0648\u0644 <strong>\u0648\u0644\u0627 \u062a\u062a\u0648\u0627\u0641\u0642 \u0627\u0644\u0623\u0639\u0631\u0627\u0636 \u0628\u0639\u062f \u0627\u0644\u0625\u0635\u0627\u0628\u0629 \u0628\u0627\u0644\u0641\u064a\u0631\u0648\u0633\u060c \u0633\u0648\u0627\u0621 \u0643\u0627\u0646 \u0644\u0648\u0646 \u0627\u0644\u0645\u0631\u064a\u0636 \u0623\u062d\u0645\u0631 \u0623\u0648 \u0623\u0635\u0641\u0631 \u0623\u0648 \u0623\u062e\u0636\u0631\u060c \u0645\u0639 \u0634\u062f\u0629 \u0627\u0644\u0645\u0631\u0636 \u0623\u062b\u0646\u0627\u0621 \u0627\u0644\u0625\u0635\u0627\u0628\u0629.<\/strong><\/span><\/p>\n\n\n\n<div class=\"wp-block-buttons aligncenter is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-background no-border-radius\" href=\"https:\/\/lin.ee\/QPnfENe\" style=\"background-color:#ba0c49\">\u0627\u0633\u062a\u0634\u0627\u0631\u0629 \u062e\u0628\u064a\u0631<\/a><\/div>\n\n\n\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-background no-border-radius\" href=\"https:\/\/w9wellness.com\/ar\/%d8%ad%d8%b2%d9%85%d8%a9-%d8%a7%d9%84%d9%85%d9%83%d9%85%d9%84%d8%a7%d8%aa-%d8%a7%d9%84%d8%ba%d8%b0%d8%a7%d8%a6%d9%8a%d8%a9-%d9%84%d9%85%d8%a7-%d8%a8%d8%b9%d8%af-%d9%83%d9%88%d9%81%d9%8a%d8%af\/\" style=\"background-color:#ba0c49\">\u0627\u0644\u0641\u064a\u062a\u0627\u0645\u064a\u0646\u0627\u062a \u0644\u0627\u0633\u062a\u0639\u0627\u062f\u0629 \u0627\u0644\u062c\u0633\u0645<\/a><\/div>\n<\/div>\n\n\n\n<p><strong><span style=\"color:#4a6051\" class=\"has-inline-color\">\u062f\u0643\u062a\u0648\u0631 \u0628\u064a\u062a\u0634\u0627\u0643 \u0648\u0648\u0646\u062c\u0648\u064a\u0633\u064a\u062a (\u062f\u0643\u062a\u0648\u0631 \u0628\u0627\u064a)<\/span><\/strong><\/p>\n\n\n\n<p><\/p>","protected":false},"excerpt":{"rendered":"<p>\u0644\u0642\u062f \u062a\u0633\u0627\u0621\u0644 \u0627\u0644\u0643\u062b\u064a\u0631 \u0645\u0646 \u0627\u0644\u0646\u0627\u0633: &quot;\u0644\u0642\u062f \u062a\u0639\u0627\u0641\u064a\u062a \u0645\u0646 \u0627\u0644\u0641\u064a\u0631\u0648\u0633 \u0648\u0644\u0643\u0646 \u0644\u0627 \u062a\u0632\u0627\u0644 \u0644\u062f\u064a \u0627\u0644\u0623\u0639\u0631\u0627\u0636&quot; \u0623\u0648 \u0628\u0639\u0636 \u0627\u0644\u0623\u0634\u062e\u0627\u0635 \u0638\u0647\u0631\u062a \u0639\u0644\u064a\u0647\u0645 \u0623\u0639\u0631\u0627\u0636 \u0642\u0644\u064a\u0644\u0629 \u0639\u0646\u062f \u0625\u0635\u0627\u0628\u062a\u0647\u0645 \u0628\u0627\u0644\u0641\u064a\u0631\u0648\u0633. \u0648\u0644\u0643\u0646 \u0628\u0639\u062f \u0627\u0644\u062a\u0639\u0627\u0641\u064a \u0648\u0638\u0647\u0648\u0631 \u0627\u0644\u0645\u0632\u064a\u062f \u0645\u0646 \u0627\u0644\u0623\u0639\u0631\u0627\u0636 \u0645\u0627 \u0647\u064a \u0627\u0644\u0646\u062f\u0628\u0627\u062a \u0627\u0644\u062a\u064a \u062a\u0631\u0643\u0647\u0627 \u0627\u0644\u0641\u064a\u0631\u0648\u0633 \u0639\u0644\u064a\u0646\u0627\u061f \u0627\u0644\u064a\u0648\u0645\u060c \u062f\u0639\u0648\u0646\u0627 \u0646\u062a\u062d\u062f\u062b \u0639\u0646 Long Covid \u062a\u0639\u0627\u0641\u0649 Long Covid \u0645\u0646 \u0627\u0644\u0625\u0635\u0627\u0628\u0629 \u0628\u0627\u0644\u0641\u064a\u0631\u0648\u0633. \u0648\u0644\u0643\u0646 \u0644\u0645\u0627\u0630\u0627 \u0644\u0627 \u062a\u0632\u0627\u0644 \u0627\u0644\u0631\u0627\u0626\u062d\u0629 \u0648\u0627\u0644\u0637\u0639\u0645 \u0643\u0645\u0627 \u0647\u0648\u061f \u0631\u0628\u0645\u0627 \u064a\u0639\u0631\u0641 \u0627\u0644\u0643\u062b\u064a\u0631 \u0645\u0646 \u0627\u0644\u0646\u0627\u0633 \u0630\u0644\u0643 \u0628\u0627\u0644\u0641\u0639\u0644. \u0628\u0639\u062f \u0627\u0644\u0625\u0635\u0627\u0628\u0629 \u0628\u0627\u0644\u0641\u064a\u0631\u0648\u0633\u060c \u0633\u062a\u0638\u0644 \u0627\u0644\u0623\u0639\u0631\u0627\u0636 \u062a\u0638\u0647\u0631 \u0643\u0645\u0627 \u0644\u0648 \u0643\u0646\u062a \u0645\u0631\u064a\u0636\u064b\u0627. \u0631\u063a\u0645 \u0623\u0646\u0646\u0627 \u0644\u0645 \u0646\u0643\u062a\u0634\u0641 \u0627\u0644\u0641\u064a\u0631\u0648\u0633 \u0628\u0639\u062f. \u062a\u0645 \u0634\u0641\u0627\u0624\u0647 \u0644\u0623\u0643\u062b\u0631 \u0645\u0646 28 \u064a\u0648\u0645\u064b\u0627 \u0623\u0648 \u0634\u0647\u0631\u064b\u0627 \u0623\u0648 \u0623\u0643\u062b\u0631. \u0647\u0646\u0627\u0643 3 \u0623\u0633\u0628\u0627\u0628 \u0631\u0626\u064a\u0633\u064a\u0629: 1. \u0645\u062a\u0644\u0627\u0632\u0645\u0629 \u0645\u0627 \u0628\u0639\u062f \u0627\u0644\u0641\u064a\u0631\u0648\u0633 \u0647\u064a \u0639\u0631\u0636 \u0628\u0639\u062f \u0627\u0644\u0625\u0635\u0627\u0628\u0629 \u0628\u0641\u064a\u0631\u0648\u0633\u060c \u0648\u0647\u0648 \u0645\u0627 \u064a\u062d\u062f\u062b \u0628\u0627\u0644\u0641\u0639\u0644 \u0645\u0639 \u0643\u0644 \u0641\u064a\u0631\u0648\u0633. \u0645\u0635\u0627\u0628 \u0628\u0627\u0644\u0623\u0646\u0641\u0644\u0648\u0646\u0632\u0627 \u0623\u0648 \u0645\u0631\u0636 \u062e\u0637\u064a\u0631 \u0648\u062f\u062e\u0648\u0644\u0647 \u0627\u0644\u0645\u0633\u062a\u0634\u0641\u0649 \u0628\u0639\u062f \u062e\u0631\u0648\u062c\u0646\u0627 \u0645\u0646 \u0627\u0644\u0645\u0633\u062a\u0634\u0641\u0649 \u0644\u0646 \u064a\u062a\u0639\u0627\u0641\u0649 \u0627\u0644\u062c\u0633\u0645 \u062c\u064a\u062f\u064b\u0627. \u0644\u0627 \u062a\u0632\u0627\u0644 \u062a\u0634\u0639\u0631 \u0628\u0627\u0644\u062a\u0639\u0628 \u0648\u0627\u0644\u0625\u0631\u0647\u0627\u0642 \u0648\u0639\u062f\u0645 \u0627\u0644\u0634\u0639\u0648\u0631 \u0628\u0627\u0644\u0627\u0646\u062a\u0639\u0627\u0634. \u064a\u0628\u062f\u0648 \u0627\u0644\u0623\u0645\u0631 \u0643\u0645\u0627 \u0644\u0648 \u0623\u0646\u0646\u0627 \u0630\u0647\u0628\u0646\u0627 \u0644\u0644\u062a\u0648 \u0644\u0644\u0642\u062a\u0627\u0644\u060c \u0648\u062e\u0636\u0646\u0627 \u062d\u0631\u0628\u064b\u0627\u060c \u0645\u062b\u0644 \u0627\u0644\u062c\u0646\u0648\u062f \u0627\u0644\u0630\u064a\u0646 \u064a\u0639\u0648\u062f\u0648\u0646 \u0648\u064a\u062d\u062a\u0627\u062c\u0648\u0646 \u0625\u0644\u0649 \u0627\u0644\u062a\u0639\u0627\u0641\u064a. \u0641\u064a \u0628\u0639\u0636 \u0627\u0644\u0623\u062d\u064a\u0627\u0646 \u062a\u0633\u062a\u0645\u0631 \u0627\u0644\u062d\u0631\u0648\u0628 \u0644\u0641\u062a\u0631\u0629 \u0637\u0648\u064a\u0644\u0629. \u0639\u0646\u062f \u0627\u0644\u0639\u0648\u062f\u0629\u060c \u0642\u062f \u064a\u0643\u0648\u0646 \u0627\u0644\u062c\u0646\u0648\u062f \u0641\u064a \u0628\u0639\u0636 \u0627\u0644\u0623\u062d\u064a\u0627\u0646 \u0645\u0631\u0647\u0642\u064a\u0646 \u062c\u0633\u062f\u064a\u064b\u0627 \u0648\u0639\u0642\u0644\u064a\u064b\u0627. \u0644\u0627 \u064a\u0632\u0627\u0644 \u064a\u062c\u0639\u0644\u0646\u064a \u0623\u0634\u0639\u0631 \u0628\u0627\u0644\u0627\u0643\u062a\u0626\u0627\u0628. \u0623\u0648 \u0623\u0646\u0647 \u0634\u062f\u064a\u062f \u0644\u062f\u0631\u062c\u0629 \u0623\u0646\u0646\u0627 \u0646\u0633\u0645\u064a\u0647 \u0627\u0636\u0637\u0631\u0627\u0628 \u0645\u0627 \u0628\u0639\u062f \u0627\u0644\u0635\u062f\u0645\u0629 (PTSD) \u0641\u064a \u0627\u0644\u0648\u0627\u0642\u0639 \u0647\u0646\u0627\u0643 \u0623\u0634\u062e\u0627\u0635 \u064a\u062a\u062d\u062f\u062b\u0648\u0646 \u0639\u0646\u0647 \u0639\u0644\u0649 \u0623\u0646\u0647 \u0627\u0636\u0637\u0631\u0627\u0628 \u0645\u0627 \u0628\u0639\u062f \u0627\u0644\u0635\u062f\u0645\u0629 \u0628\u0639\u062f \u0625\u0635\u0627\u0628\u062a\u0647\u0645 \u0628\u0641\u064a\u0631\u0648\u0633 [...].<\/p>","protected":false},"author":2,"featured_media":19883,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[45,139,136,120],"tags":[138,140],"class_list":["post-17562","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-health-hub","category-long-covid","category-probiotics","category-special-treatments","tag-long-covid","tag-140"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u0e25\u0e2d\u0e07 \u0e42\u0e04\u0e27\u0e34\u0e14 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e04\u0e38\u0e13\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e2a\u0e35\u0e44\u0e2b\u0e19\u0e01\u0e47\u0e21\u0e35\u0e20\u0e32\u0e27\u0e30 Long Covid - W9wellness<\/title>\n<meta name=\"description\" content=\"\u0e25\u0e2d\u0e07 \u0e42\u0e04\u0e27\u0e34\u0e14 \u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e15\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e23\u0e30\u0e22\u0e30\u0e22\u0e32\u0e27\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e17\u0e38\u0e01\u0e2a\u0e35 \u0e41\u0e21\u0e49\u0e27\u0e48\u0e32\u0e40\u0e23\u0e32\u0e08\u0e30\u0e15\u0e23\u0e27\u0e08\u0e44\u0e21\u0e48\u0e1e\u0e1a\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e41\u0e25\u0e49\u0e27 \u0e23\u0e31\u0e01\u0e29\u0e32\u0e2b\u0e32\u0e22\u0e40\u0e01\u0e34\u0e19\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e19\u0e36\u0e07\u0e02\u0e36\u0e49\u0e19\u0e44\u0e1b \u0e41\u0e15\u0e48\u0e08\u0e30\u0e22\u0e31\u0e07\u0e21\u0e35\u0e2d\u0e32\u0e01\u0e32\u0e23\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e1b\u0e48\u0e27\u0e22\u0e2d\u0e22\u0e39\u0e48\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/w9wellness.com\/ar\/\u0645\u0627-\u0628\u0639\u062f-\u0643\u0648\u0641\u064a\u062f-19\/\" \/>\n<meta property=\"og:locale\" content=\"ar_AR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e25\u0e2d\u0e07 \u0e42\u0e04\u0e27\u0e34\u0e14 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e04\u0e38\u0e13\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e2a\u0e35\u0e44\u0e2b\u0e19\u0e01\u0e47\u0e21\u0e35\u0e20\u0e32\u0e27\u0e30 Long Covid - W9wellness\" \/>\n<meta property=\"og:description\" content=\"\u0e25\u0e2d\u0e07 \u0e42\u0e04\u0e27\u0e34\u0e14 \u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e15\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e23\u0e30\u0e22\u0e30\u0e22\u0e32\u0e27\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e17\u0e38\u0e01\u0e2a\u0e35 \u0e41\u0e21\u0e49\u0e27\u0e48\u0e32\u0e40\u0e23\u0e32\u0e08\u0e30\u0e15\u0e23\u0e27\u0e08\u0e44\u0e21\u0e48\u0e1e\u0e1a\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e41\u0e25\u0e49\u0e27 \u0e23\u0e31\u0e01\u0e29\u0e32\u0e2b\u0e32\u0e22\u0e40\u0e01\u0e34\u0e19\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e19\u0e36\u0e07\u0e02\u0e36\u0e49\u0e19\u0e44\u0e1b \u0e41\u0e15\u0e48\u0e08\u0e30\u0e22\u0e31\u0e07\u0e21\u0e35\u0e2d\u0e32\u0e01\u0e32\u0e23\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e1b\u0e48\u0e27\u0e22\u0e2d\u0e22\u0e39\u0e48\" \/>\n<meta property=\"og:url\" content=\"https:\/\/w9wellness.com\/ar\/\u0645\u0627-\u0628\u0639\u062f-\u0643\u0648\u0641\u064a\u062f-19\/\" \/>\n<meta property=\"og:site_name\" content=\"W9wellness\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-17T06:56:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-06T07:38:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/w9wellness.com\/wp-content\/uploads\/2022\/02\/\u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19-\u0e23\u0e31\u0e01\u0e29\u0e32-\u0e25\u0e2d\u0e07\u0e42\u0e04\u0e27\u0e34\u0e14-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"w9wellness\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u0643\u064f\u062a\u0628 \u0628\u0648\u0627\u0633\u0637\u0629\" \/>\n\t<meta name=\"twitter:data1\" content=\"w9wellness\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/w9wellness.com\/post-covid-19\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/w9wellness.com\/post-covid-19\/\"},\"author\":{\"name\":\"w9wellness\",\"@id\":\"https:\/\/new.w9wellness.com\/#\/schema\/person\/1e8f78804d23c1098e3ffa305f9ea157\"},\"headline\":\"\u0e25\u0e2d\u0e07 \u0e42\u0e04\u0e27\u0e34\u0e14 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e04\u0e38\u0e13\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e2a\u0e35\u0e44\u0e2b\u0e19\u0e01\u0e47\u0e21\u0e35 \u0e20\u0e32\u0e27\u0e30 Long Covid \u0e44\u0e14\u0e49\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e01\u0e31\u0e19\",\"datePublished\":\"2022-02-17T06:56:23+00:00\",\"dateModified\":\"2023-09-06T07:38:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/w9wellness.com\/post-covid-19\/\"},\"wordCount\":32,\"publisher\":{\"@id\":\"https:\/\/new.w9wellness.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/w9wellness.com\/post-covid-19\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/w9wellness.com\/wp-content\/uploads\/2022\/02\/\u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19-\u0e23\u0e31\u0e01\u0e29\u0e32-\u0e25\u0e2d\u0e07\u0e42\u0e04\u0e27\u0e34\u0e14-1.jpg\",\"keywords\":[\"Long Covid\",\"\u0e25\u0e2d\u0e07\u0e42\u0e04\u0e27\u0e34\u0e14\"],\"articleSection\":[\"Healthy Hub\",\"Long COVID\",\"Probiotics\",\"Special Treatments\"],\"inLanguage\":\"ar\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/w9wellness.com\/post-covid-19\/\",\"url\":\"https:\/\/w9wellness.com\/post-covid-19\/\",\"name\":\"\u0e25\u0e2d\u0e07 \u0e42\u0e04\u0e27\u0e34\u0e14 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e04\u0e38\u0e13\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e2a\u0e35\u0e44\u0e2b\u0e19\u0e01\u0e47\u0e21\u0e35\u0e20\u0e32\u0e27\u0e30 Long Covid - W9wellness\",\"isPartOf\":{\"@id\":\"https:\/\/new.w9wellness.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/w9wellness.com\/post-covid-19\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/w9wellness.com\/post-covid-19\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/w9wellness.com\/wp-content\/uploads\/2022\/02\/\u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19-\u0e23\u0e31\u0e01\u0e29\u0e32-\u0e25\u0e2d\u0e07\u0e42\u0e04\u0e27\u0e34\u0e14-1.jpg\",\"datePublished\":\"2022-02-17T06:56:23+00:00\",\"dateModified\":\"2023-09-06T07:38:44+00:00\",\"description\":\"\u0e25\u0e2d\u0e07 \u0e42\u0e04\u0e27\u0e34\u0e14 \u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e15\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e23\u0e30\u0e22\u0e30\u0e22\u0e32\u0e27\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e17\u0e38\u0e01\u0e2a\u0e35 \u0e41\u0e21\u0e49\u0e27\u0e48\u0e32\u0e40\u0e23\u0e32\u0e08\u0e30\u0e15\u0e23\u0e27\u0e08\u0e44\u0e21\u0e48\u0e1e\u0e1a\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e41\u0e25\u0e49\u0e27 \u0e23\u0e31\u0e01\u0e29\u0e32\u0e2b\u0e32\u0e22\u0e40\u0e01\u0e34\u0e19\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e19\u0e36\u0e07\u0e02\u0e36\u0e49\u0e19\u0e44\u0e1b \u0e41\u0e15\u0e48\u0e08\u0e30\u0e22\u0e31\u0e07\u0e21\u0e35\u0e2d\u0e32\u0e01\u0e32\u0e23\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e1b\u0e48\u0e27\u0e22\u0e2d\u0e22\u0e39\u0e48\",\"breadcrumb\":{\"@id\":\"https:\/\/w9wellness.com\/post-covid-19\/#breadcrumb\"},\"inLanguage\":\"ar\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/w9wellness.com\/post-covid-19\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\/\/w9wellness.com\/post-covid-19\/#primaryimage\",\"url\":\"https:\/\/w9wellness.com\/wp-content\/uploads\/2022\/02\/\u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19-\u0e23\u0e31\u0e01\u0e29\u0e32-\u0e25\u0e2d\u0e07\u0e42\u0e04\u0e27\u0e34\u0e14-1.jpg\",\"contentUrl\":\"https:\/\/w9wellness.com\/wp-content\/uploads\/2022\/02\/\u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19-\u0e23\u0e31\u0e01\u0e29\u0e32-\u0e25\u0e2d\u0e07\u0e42\u0e04\u0e27\u0e34\u0e14-1.jpg\",\"width\":1200,\"height\":628,\"caption\":\"\u0e2d\u0e32\u0e01\u0e32\u0e23 \u0e25\u0e2d\u0e07\u0e42\u0e04\u0e27\u0e34\u0e14\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/w9wellness.com\/post-covid-19\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/w9wellness.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e25\u0e2d\u0e07 \u0e42\u0e04\u0e27\u0e34\u0e14 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e04\u0e38\u0e13\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e2a\u0e35\u0e44\u0e2b\u0e19\u0e01\u0e47\u0e21\u0e35 \u0e20\u0e32\u0e27\u0e30 Long Covid \u0e44\u0e14\u0e49\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e01\u0e31\u0e19\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/new.w9wellness.com\/#website\",\"url\":\"https:\/\/new.w9wellness.com\/\",\"name\":\"W9wellness\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/new.w9wellness.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/new.w9wellness.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ar\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/new.w9wellness.com\/#organization\",\"name\":\"W9wellness\",\"url\":\"https:\/\/new.w9wellness.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\/\/new.w9wellness.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/w9wellness.com\/wp-content\/uploads\/2023\/07\/cropped-w9logo.png\",\"contentUrl\":\"https:\/\/w9wellness.com\/wp-content\/uploads\/2023\/07\/cropped-w9logo.png\",\"width\":50,\"height\":50,\"caption\":\"W9wellness\"},\"image\":{\"@id\":\"https:\/\/new.w9wellness.com\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/new.w9wellness.com\/#\/schema\/person\/1e8f78804d23c1098e3ffa305f9ea157\",\"name\":\"w9wellness\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ar\",\"@id\":\"https:\/\/new.w9wellness.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/02b75c846ddd120150b00538e29d6eb6ac8a7c01ae701b1f5bb7a8818dd5e8ab?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/02b75c846ddd120150b00538e29d6eb6ac8a7c01ae701b1f5bb7a8818dd5e8ab?s=96&d=mm&r=g\",\"caption\":\"w9wellness\"},\"url\":\"https:\/\/w9wellness.com\/ar\/author\/w9wellness\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0643\u0648\u0641\u064a\u062f \u0637\u0648\u064a\u0644 \u0627\u0644\u0623\u0645\u062f: \u0628\u063a\u0636 \u0627\u0644\u0646\u0638\u0631 \u0639\u0646 \u0644\u0648\u0646\u0643\u060c \u0641\u0623\u0646\u062a \u0645\u0635\u0627\u0628 \u0628\u0643\u0648\u0641\u064a\u062f \u0637\u0648\u064a\u0644 \u0627\u0644\u0623\u0645\u062f - W9wellness","description":"\u0627\u0644\u062a\u0623\u062b\u064a\u0631\u0627\u062a \u0627\u0644\u0635\u062d\u064a\u0629 \u0637\u0648\u064a\u0644\u0629 \u0627\u0644\u0645\u062f\u0649 \u0644\u0645\u0631\u0636 \u0643\u0648\u0641\u064a\u062f-19 \u0639\u0644\u0649 \u062c\u0645\u064a\u0639 \u0627\u0644\u0645\u0631\u0636\u0649\u060c \u062d\u062a\u0649 \u0644\u0648 \u0644\u0645 \u064a\u062a\u0645 \u0627\u0643\u062a\u0634\u0627\u0641 \u0627\u0644\u0641\u064a\u0631\u0648\u0633 \u0648\u062a\u0645 \u0634\u0641\u0627\u0621 \u0627\u0644\u0645\u0631\u064a\u0636 \u0644\u0623\u0643\u062b\u0631 \u0645\u0646 \u0634\u0647\u0631\u060c \u0641\u0625\u0646\u0647\u0645 \u0633\u064a\u0638\u0644\u0648\u0646 \u064a\u0639\u0627\u0646\u0648\u0646 \u0645\u0646 \u0623\u0639\u0631\u0627\u0636 \u0645\u0634\u0627\u0628\u0647\u0629 \u0644\u0644\u0645\u0631\u0636.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/w9wellness.com\/ar\/\u0645\u0627-\u0628\u0639\u062f-\u0643\u0648\u0641\u064a\u062f-19\/","og_locale":"ar_AR","og_type":"article","og_title":"\u0e25\u0e2d\u0e07 \u0e42\u0e04\u0e27\u0e34\u0e14 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e04\u0e38\u0e13\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e2a\u0e35\u0e44\u0e2b\u0e19\u0e01\u0e47\u0e21\u0e35\u0e20\u0e32\u0e27\u0e30 Long Covid - W9wellness","og_description":"\u0e25\u0e2d\u0e07 \u0e42\u0e04\u0e27\u0e34\u0e14 \u0e1c\u0e25\u0e01\u0e23\u0e30\u0e17\u0e1a\u0e15\u0e48\u0e2d\u0e2a\u0e38\u0e02\u0e20\u0e32\u0e1e\u0e23\u0e30\u0e22\u0e30\u0e22\u0e32\u0e27\u0e02\u0e2d\u0e07\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e17\u0e38\u0e01\u0e2a\u0e35 \u0e41\u0e21\u0e49\u0e27\u0e48\u0e32\u0e40\u0e23\u0e32\u0e08\u0e30\u0e15\u0e23\u0e27\u0e08\u0e44\u0e21\u0e48\u0e1e\u0e1a\u0e40\u0e0a\u0e37\u0e49\u0e2d\u0e41\u0e25\u0e49\u0e27 \u0e23\u0e31\u0e01\u0e29\u0e32\u0e2b\u0e32\u0e22\u0e40\u0e01\u0e34\u0e19\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e19\u0e36\u0e07\u0e02\u0e36\u0e49\u0e19\u0e44\u0e1b \u0e41\u0e15\u0e48\u0e08\u0e30\u0e22\u0e31\u0e07\u0e21\u0e35\u0e2d\u0e32\u0e01\u0e32\u0e23\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e1b\u0e48\u0e27\u0e22\u0e2d\u0e22\u0e39\u0e48","og_url":"https:\/\/w9wellness.com\/ar\/\u0645\u0627-\u0628\u0639\u062f-\u0643\u0648\u0641\u064a\u062f-19\/","og_site_name":"W9wellness","article_published_time":"2022-02-17T06:56:23+00:00","article_modified_time":"2023-09-06T07:38:44+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/w9wellness.com\/wp-content\/uploads\/2022\/02\/\u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19-\u0e23\u0e31\u0e01\u0e29\u0e32-\u0e25\u0e2d\u0e07\u0e42\u0e04\u0e27\u0e34\u0e14-1.jpg","type":"image\/jpeg"}],"author":"w9wellness","twitter_card":"summary_large_image","twitter_misc":{"\u0643\u064f\u062a\u0628 \u0628\u0648\u0627\u0633\u0637\u0629":"w9wellness"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/w9wellness.com\/post-covid-19\/#article","isPartOf":{"@id":"https:\/\/w9wellness.com\/post-covid-19\/"},"author":{"name":"w9wellness","@id":"https:\/\/new.w9wellness.com\/#\/schema\/person\/1e8f78804d23c1098e3ffa305f9ea157"},"headline":"\u0e25\u0e2d\u0e07 \u0e42\u0e04\u0e27\u0e34\u0e14 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e04\u0e38\u0e13\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e2a\u0e35\u0e44\u0e2b\u0e19\u0e01\u0e47\u0e21\u0e35 \u0e20\u0e32\u0e27\u0e30 Long Covid \u0e44\u0e14\u0e49\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e01\u0e31\u0e19","datePublished":"2022-02-17T06:56:23+00:00","dateModified":"2023-09-06T07:38:44+00:00","mainEntityOfPage":{"@id":"https:\/\/w9wellness.com\/post-covid-19\/"},"wordCount":32,"publisher":{"@id":"https:\/\/new.w9wellness.com\/#organization"},"image":{"@id":"https:\/\/w9wellness.com\/post-covid-19\/#primaryimage"},"thumbnailUrl":"https:\/\/w9wellness.com\/wp-content\/uploads\/2022\/02\/\u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19-\u0e23\u0e31\u0e01\u0e29\u0e32-\u0e25\u0e2d\u0e07\u0e42\u0e04\u0e27\u0e34\u0e14-1.jpg","keywords":["Long Covid","\u0e25\u0e2d\u0e07\u0e42\u0e04\u0e27\u0e34\u0e14"],"articleSection":["Healthy Hub","Long COVID","Probiotics","Special Treatments"],"inLanguage":"ar"},{"@type":"WebPage","@id":"https:\/\/w9wellness.com\/post-covid-19\/","url":"https:\/\/w9wellness.com\/post-covid-19\/","name":"\u0643\u0648\u0641\u064a\u062f \u0637\u0648\u064a\u0644 \u0627\u0644\u0623\u0645\u062f: \u0628\u063a\u0636 \u0627\u0644\u0646\u0638\u0631 \u0639\u0646 \u0644\u0648\u0646\u0643\u060c \u0641\u0623\u0646\u062a \u0645\u0635\u0627\u0628 \u0628\u0643\u0648\u0641\u064a\u062f \u0637\u0648\u064a\u0644 \u0627\u0644\u0623\u0645\u062f - W9wellness","isPartOf":{"@id":"https:\/\/new.w9wellness.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/w9wellness.com\/post-covid-19\/#primaryimage"},"image":{"@id":"https:\/\/w9wellness.com\/post-covid-19\/#primaryimage"},"thumbnailUrl":"https:\/\/w9wellness.com\/wp-content\/uploads\/2022\/02\/\u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19-\u0e23\u0e31\u0e01\u0e29\u0e32-\u0e25\u0e2d\u0e07\u0e42\u0e04\u0e27\u0e34\u0e14-1.jpg","datePublished":"2022-02-17T06:56:23+00:00","dateModified":"2023-09-06T07:38:44+00:00","description":"\u0627\u0644\u062a\u0623\u062b\u064a\u0631\u0627\u062a \u0627\u0644\u0635\u062d\u064a\u0629 \u0637\u0648\u064a\u0644\u0629 \u0627\u0644\u0645\u062f\u0649 \u0644\u0645\u0631\u0636 \u0643\u0648\u0641\u064a\u062f-19 \u0639\u0644\u0649 \u062c\u0645\u064a\u0639 \u0627\u0644\u0645\u0631\u0636\u0649\u060c \u062d\u062a\u0649 \u0644\u0648 \u0644\u0645 \u064a\u062a\u0645 \u0627\u0643\u062a\u0634\u0627\u0641 \u0627\u0644\u0641\u064a\u0631\u0648\u0633 \u0648\u062a\u0645 \u0634\u0641\u0627\u0621 \u0627\u0644\u0645\u0631\u064a\u0636 \u0644\u0623\u0643\u062b\u0631 \u0645\u0646 \u0634\u0647\u0631\u060c \u0641\u0625\u0646\u0647\u0645 \u0633\u064a\u0638\u0644\u0648\u0646 \u064a\u0639\u0627\u0646\u0648\u0646 \u0645\u0646 \u0623\u0639\u0631\u0627\u0636 \u0645\u0634\u0627\u0628\u0647\u0629 \u0644\u0644\u0645\u0631\u0636.","breadcrumb":{"@id":"https:\/\/w9wellness.com\/post-covid-19\/#breadcrumb"},"inLanguage":"ar","potentialAction":[{"@type":"ReadAction","target":["https:\/\/w9wellness.com\/post-covid-19\/"]}]},{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/w9wellness.com\/post-covid-19\/#primaryimage","url":"https:\/\/w9wellness.com\/wp-content\/uploads\/2022\/02\/\u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19-\u0e23\u0e31\u0e01\u0e29\u0e32-\u0e25\u0e2d\u0e07\u0e42\u0e04\u0e27\u0e34\u0e14-1.jpg","contentUrl":"https:\/\/w9wellness.com\/wp-content\/uploads\/2022\/02\/\u0e27\u0e34\u0e15\u0e32\u0e21\u0e34\u0e19-\u0e23\u0e31\u0e01\u0e29\u0e32-\u0e25\u0e2d\u0e07\u0e42\u0e04\u0e27\u0e34\u0e14-1.jpg","width":1200,"height":628,"caption":"\u0e2d\u0e32\u0e01\u0e32\u0e23 \u0e25\u0e2d\u0e07\u0e42\u0e04\u0e27\u0e34\u0e14"},{"@type":"BreadcrumbList","@id":"https:\/\/w9wellness.com\/post-covid-19\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/w9wellness.com\/"},{"@type":"ListItem","position":2,"name":"\u0e25\u0e2d\u0e07 \u0e42\u0e04\u0e27\u0e34\u0e14 \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e04\u0e38\u0e13\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e1c\u0e39\u0e49\u0e1b\u0e48\u0e27\u0e22\u0e2a\u0e35\u0e44\u0e2b\u0e19\u0e01\u0e47\u0e21\u0e35 \u0e20\u0e32\u0e27\u0e30 Long Covid \u0e44\u0e14\u0e49\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e01\u0e31\u0e19"}]},{"@type":"WebSite","@id":"https:\/\/new.w9wellness.com\/#website","url":"https:\/\/new.w9wellness.com\/","name":"W9wellness","description":"","publisher":{"@id":"https:\/\/new.w9wellness.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/new.w9wellness.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ar"},{"@type":"Organization","@id":"https:\/\/new.w9wellness.com\/#organization","name":"W9wellness","url":"https:\/\/new.w9wellness.com\/","logo":{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/new.w9wellness.com\/#\/schema\/logo\/image\/","url":"https:\/\/w9wellness.com\/wp-content\/uploads\/2023\/07\/cropped-w9logo.png","contentUrl":"https:\/\/w9wellness.com\/wp-content\/uploads\/2023\/07\/cropped-w9logo.png","width":50,"height":50,"caption":"W9wellness"},"image":{"@id":"https:\/\/new.w9wellness.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/new.w9wellness.com\/#\/schema\/person\/1e8f78804d23c1098e3ffa305f9ea157","name":"w9wellness","image":{"@type":"ImageObject","inLanguage":"ar","@id":"https:\/\/new.w9wellness.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/02b75c846ddd120150b00538e29d6eb6ac8a7c01ae701b1f5bb7a8818dd5e8ab?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/02b75c846ddd120150b00538e29d6eb6ac8a7c01ae701b1f5bb7a8818dd5e8ab?s=96&d=mm&r=g","caption":"w9wellness"},"url":"https:\/\/w9wellness.com\/ar\/author\/w9wellness\/"}]}},"_links":{"self":[{"href":"https:\/\/w9wellness.com\/ar\/wp-json\/wp\/v2\/posts\/17562","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/w9wellness.com\/ar\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/w9wellness.com\/ar\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/w9wellness.com\/ar\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/w9wellness.com\/ar\/wp-json\/wp\/v2\/comments?post=17562"}],"version-history":[{"count":1,"href":"https:\/\/w9wellness.com\/ar\/wp-json\/wp\/v2\/posts\/17562\/revisions"}],"predecessor-version":[{"id":24602,"href":"https:\/\/w9wellness.com\/ar\/wp-json\/wp\/v2\/posts\/17562\/revisions\/24602"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/w9wellness.com\/ar\/wp-json\/wp\/v2\/media\/19883"}],"wp:attachment":[{"href":"https:\/\/w9wellness.com\/ar\/wp-json\/wp\/v2\/media?parent=17562"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/w9wellness.com\/ar\/wp-json\/wp\/v2\/categories?post=17562"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/w9wellness.com\/ar\/wp-json\/wp\/v2\/tags?post=17562"}],"curies":[{"name":"\u0648\u0648\u0631\u062f\u0628\u0631\u064a\u0633","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}